{"id":44,"date":"2020-02-10T22:44:46","date_gmt":"2020-02-10T22:44:46","guid":{"rendered":"http:\/\/zikzag.wgl-demo.net\/?page_id=44"},"modified":"2020-02-10T22:44:46","modified_gmt":"2020-02-10T22:44:46","slug":"portfolio-masonry","status":"publish","type":"page","link":"https:\/\/soycaribe.com\/index.php\/portfolio-masonry\/","title":{"rendered":"Portfolio Masonry"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"44\" class=\"elementor elementor-44\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39a3efa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39a3efa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a878802\" data-id=\"a878802\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f5c991 acenter elementor-widget elementor-widget-wgl-double-headings\" data-id=\"1f5c991\" data-element_type=\"widget\" data-widget_type=\"wgl-double-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wgl-double_heading\"><div class=\"dbl__subtitle\"><span>Business portfolio<\/span><\/div><h3 class=\"dbl__title-wrapper\"><span class=\"dbl__title\">Our Case Studies<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8411906 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8411906\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45b61cd\" data-id=\"45b61cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8e77a5 elementor-widget elementor-widget-spacer\" data-id=\"e8e77a5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e06de24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e06de24\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ca3938\" data-id=\"0ca3938\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4782f35 elementor-widget elementor-widget-text-editor\" data-id=\"4782f35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tWe are specialists in both economics and information technologies and we apply our full range of talent to creating the perfect solution for each client\u2019s needs.\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41f5936 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41f5936\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21f0bb3\" data-id=\"21f0bb3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dafe26c elementor-widget elementor-widget-spacer\" data-id=\"dafe26c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8087b7c elementor-widget elementor-widget-wgl-portfolio\" data-id=\"8087b7c\" data-element_type=\"widget\" data-widget_type=\"wgl-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"wgl_cpt_section\"><div class=\"wgl-portfolio\" id=\"portfolio_module_6a57fc892c5db\"><div class=\"portfolio__filter isotope-filter filter-center\"><a href=\"#\" data-filter=\".item\" class=\"active\">All Works<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio-category\/corporate\/\" data-filter=\".corporate\">corporate<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio-category\/finance\/\" data-filter=\".finance\">finance<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio-category\/marketing\/\" data-filter=\".marketing\">marketing<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio-category\/startup\/\" data-filter=\".startup\">startup<span class=\"number_filter\"><\/span><\/a><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio-category\/strategy\/\" data-filter=\".strategy\">strategy<span class=\"number_filter\"><\/span><\/a><\/div><div class=\"wgl-portfolio_wrapper\"><div class=\"wgl-portfolio_container container-grid row isotope appear-animation anim-slide-top\"  style=\"margin-right:-15px; margin-left:-15px; margin-bottom:-30px;\"><div class=\"wgl-portfolio-list_item-size\" style=\"width: 25%;\"><\/div><article class=\"wgl-portfolio-list_item item wgl_col-6 corporate finance\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_01-740x740.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/information-technology\/\" target=\"_blank\" >Information Technology<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/corporate\/ class=\"portfolio-category\">corporate<\/a><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/finance\/ class=\"portfolio-category\">finance<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/information-technology\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-6 startup\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_02-740x350.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/mobile-app-startup\/\" target=\"_blank\" >Mobile App Startup<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/startup\/ class=\"portfolio-category\">startup<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/mobile-app-startup\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-3 marketing strategy\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_03-740x740.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/people-professionalism\/\" target=\"_blank\" >People Professionalism<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/marketing\/ class=\"portfolio-category\">marketing<\/a><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/strategy\/ class=\"portfolio-category\">strategy<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/people-professionalism\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-3 corporate strategy\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_04-740x740.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/new-business-innovation\/\" target=\"_blank\" >New Business Innovation<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/corporate\/ class=\"portfolio-category\">corporate<\/a><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/strategy\/ class=\"portfolio-category\">strategy<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/new-business-innovation\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-6 startup\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_05-740x740.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/customer-strategy\/\" target=\"_blank\" >Customer Strategy<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/startup\/ class=\"portfolio-category\">startup<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/customer-strategy\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-6 marketing\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_06-740x350.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/business-planning\/\" target=\"_blank\" >Business Planning<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/marketing\/ class=\"portfolio-category\">marketing<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/business-planning\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-3 corporate strategy\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_07-740x740.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/partnership-system\/\" target=\"_blank\" >Partnership System<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/corporate\/ class=\"portfolio-category\">corporate<\/a><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/strategy\/ class=\"portfolio-category\">strategy<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/partnership-system\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><article class=\"wgl-portfolio-list_item item wgl_col-3 finance marketing\"  style=\"padding-right:15px; padding-left:15px; padding-bottom:30px\"><div class=\"wgl-portfolio-item_wrapper inside_image simple_animation\"><div class=\"wgl-portfolio-item_image\"><img decoding=\"async\" src=\"https:\/\/soycaribe.com\/wp-content\/uploads\/2020\/02\/portfolio_08-740x740.jpg\"  alt=\"\" \/><\/div><div class=\"wgl-portfolio-item_description\"><div class=\"portfolio__description\"><div class=\"portfolio__item-title\"><h4 class=\"title\"><a href=\"https:\/\/soycaribe.com\/index.php\/portfolio\/flexibility-adaptibility\/\" target=\"_blank\" >Flexibility &#038; Adaptibility<\/a><\/h4><\/div><div class=\"portfolio__item-meta\"><span class=\"post_cats\"><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/finance\/ class=\"portfolio-category\">finance<\/a><a href=https:\/\/soycaribe.com\/index.php\/portfolio-category\/marketing\/ class=\"portfolio-category\">marketing<\/a><\/span><\/div><\/div><a href='https:\/\/soycaribe.com\/index.php\/portfolio\/flexibility-adaptibility\/' target=\"_blank\"  class='portfolio_link single_link'><\/a><\/div><div class=\"overlay\"><\/div><\/div><\/article><\/div><\/div><div class=\"clear\"><\/div><div class=\"load_more_wrapper\"><div class=\"button_wrapper\"><a href=\"#\" class=\"load_more_item\"><span>Load More<\/span><\/a><\/div><form class=\"posts_grid_ajax\"><input type='hidden' class='ajax_data' name='6a57fc892ed9a_ajax_data' value='{&quot;portfolio_layout&quot;:&quot;masonry3&quot;,&quot;posts_per_row&quot;:null,&quot;show_filter&quot;:&quot;yes&quot;,&quot;items_load&quot;:&quot;4&quot;,&quot;name_load_more&quot;:&quot;Load More&quot;,&quot;navigation&quot;:&quot;load_more&quot;,&quot;add_animation&quot;:&quot;yes&quot;,&quot;appear_animation&quot;:&quot;slide-top&quot;,&quot;number_of_posts&quot;:8,&quot;order&quot;:&quot;ASC&quot;,&quot;load_more_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;48&quot;,&quot;right&quot;:&quot;0&quot;,&quot;bottom&quot;:&quot;0&quot;,&quot;left&quot;:&quot;0&quot;,&quot;isLinked&quot;:false},&quot;headings_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;8&quot;,&quot;right&quot;:&quot;10&quot;,&quot;bottom&quot;:&quot;8&quot;,&quot;left&quot;:&quot;10&quot;,&quot;isLinked&quot;:false},&quot;custom_fonts_portfolio_headings_typography&quot;:&quot;custom&quot;,&quot;custom_fonts_portfolio_headings_font_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;custom_fonts_portfolio_headings_line_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:1.13300000000000000710542735760100185871124267578125,&quot;sizes&quot;:[]},&quot;custom_hover_headings_color&quot;:&quot;rgba(255, 255, 255, 0.72)&quot;,&quot;grid_gap&quot;:&quot;30px&quot;,&quot;filter_align&quot;:&quot;center&quot;,&quot;crop_images&quot;:&quot;yes&quot;,&quot;item_link&quot;:null,&quot;link_position&quot;:null,&quot;link_align&quot;:null,&quot;nav_align&quot;:null,&quot;img_click_action&quot;:&quot;single&quot;,&quot;single_link_title&quot;:&quot;yes&quot;,&quot;link_target&quot;:&quot;yes&quot;,&quot;info_position&quot;:&quot;inside_image&quot;,&quot;image_anim&quot;:&quot;simple&quot;,&quot;horizontal_align&quot;:null,&quot;gallery_mode&quot;:&quot;&quot;,&quot;show_portfolio_title&quot;:&quot;yes&quot;,&quot;show_meta_categories&quot;:&quot;yes&quot;,&quot;show_content&quot;:&quot;&quot;,&quot;content_letter_count&quot;:null,&quot;portfolio_icon_type&quot;:null,&quot;portfolio_icon_fontawesome&quot;:null,&quot;autoplay&quot;:null,&quot;autoplay_speed&quot;:null,&quot;c_infinite_loop&quot;:null,&quot;c_slide_per_single&quot;:null,&quot;center_mode&quot;:null,&quot;center_info&quot;:null,&quot;variable_width&quot;:null,&quot;use_pagination&quot;:null,&quot;pag_type&quot;:null,&quot;custom_pag_color&quot;:null,&quot;pag_color&quot;:null,&quot;use_prev_next&quot;:null,&quot;arrows_center_mode&quot;:null,&quot;custom_resp&quot;:null,&quot;resp_medium&quot;:null,&quot;resp_medium_slides&quot;:null,&quot;resp_tablets&quot;:null,&quot;resp_tablets_slides&quot;:null,&quot;resp_mobile&quot;:null,&quot;resp_mobile_slides&quot;:null,&quot;order_by&quot;:&quot;date&quot;,&quot;taxonomies&quot;:&quot;&quot;,&quot;exclude_taxonomies&quot;:&quot;&quot;,&quot;by_posts&quot;:&quot;&quot;,&quot;exclude_any&quot;:&quot;&quot;,&quot;author&quot;:&quot;&quot;,&quot;exclude_author&quot;:&quot;&quot;,&quot;description_color&quot;:null,&quot;description_color_b&quot;:null,&quot;description_image&quot;:null,&quot;description_video_link&quot;:null,&quot;description_video_start&quot;:null,&quot;description_video_end&quot;:null,&quot;description_play_once&quot;:null,&quot;description_play_on_mobile&quot;:null,&quot;description_privacy_mode&quot;:null,&quot;description_slideshow_gallery&quot;:null,&quot;description_slideshow_loop&quot;:null,&quot;description_slideshow_slide_duration&quot;:null,&quot;description_slideshow_slide_transition&quot;:null,&quot;description_slideshow_transition_duration&quot;:null,&quot;description_slideshow_lazyload&quot;:null,&quot;description_slideshow_ken_burns&quot;:null,&quot;description_slideshow_ken_burns_zoom_direction&quot;:null,&quot;custom_image_mask_color_color&quot;:null,&quot;custom_image_mask_color_color_b&quot;:null,&quot;custom_image_mask_color_image&quot;:null,&quot;custom_image_mask_color_video_link&quot;:null,&quot;custom_image_mask_color_video_start&quot;:null,&quot;custom_image_mask_color_video_end&quot;:null,&quot;custom_image_mask_color_play_once&quot;:null,&quot;custom_image_mask_color_play_on_mobile&quot;:null,&quot;custom_image_mask_color_privacy_mode&quot;:null,&quot;custom_image_mask_color_slideshow_gallery&quot;:null,&quot;custom_image_mask_color_slideshow_loop&quot;:null,&quot;custom_image_mask_color_slideshow_slide_duration&quot;:null,&quot;custom_image_mask_color_slideshow_slide_transition&quot;:null,&quot;custom_image_mask_color_slideshow_transition_duration&quot;:null,&quot;custom_image_mask_color_slideshow_lazyload&quot;:null,&quot;custom_image_mask_color_slideshow_ken_burns&quot;:null,&quot;custom_image_mask_color_slideshow_ken_burns_zoom_direction&quot;:null,&quot;custom_desc_mask_color_color&quot;:null,&quot;custom_desc_mask_color_color_b&quot;:null,&quot;custom_desc_mask_color_image&quot;:null,&quot;custom_desc_mask_color_video_link&quot;:null,&quot;custom_desc_mask_color_video_start&quot;:null,&quot;custom_desc_mask_color_video_end&quot;:null,&quot;custom_desc_mask_color_play_once&quot;:null,&quot;custom_desc_mask_color_play_on_mobile&quot;:null,&quot;custom_desc_mask_color_privacy_mode&quot;:null,&quot;custom_desc_mask_color_slideshow_gallery&quot;:null,&quot;custom_desc_mask_color_slideshow_loop&quot;:null,&quot;custom_desc_mask_color_slideshow_slide_duration&quot;:null,&quot;custom_desc_mask_color_slideshow_slide_transition&quot;:null,&quot;custom_desc_mask_color_slideshow_transition_duration&quot;:null,&quot;custom_desc_mask_color_slideshow_lazyload&quot;:null,&quot;custom_desc_mask_color_slideshow_ken_burns&quot;:null,&quot;custom_desc_mask_color_slideshow_ken_burns_zoom_direction&quot;:null,&quot;_title&quot;:&quot;&quot;,&quot;_element_width&quot;:&quot;&quot;,&quot;_element_width_tablet&quot;:&quot;&quot;,&quot;_element_width_mobile&quot;:&quot;&quot;,&quot;_position&quot;:&quot;&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;_css_classes&quot;:&quot;&quot;,&quot;_element_cache&quot;:&quot;&quot;,&quot;_animation&quot;:&quot;&quot;,&quot;_animation_tablet&quot;:&quot;&quot;,&quot;_animation_mobile&quot;:&quot;&quot;,&quot;animation_duration&quot;:null,&quot;_animation_delay&quot;:null,&quot;_transform_rotate_popover&quot;:&quot;&quot;,&quot;_transform_rotateZ_effect&quot;:null,&quot;_transform_rotateZ_effect_tablet&quot;:null,&quot;_transform_rotateZ_effect_mobile&quot;:null,&quot;_transform_rotate_3d&quot;:null,&quot;_transform_rotateX_effect&quot;:null,&quot;_transform_rotateX_effect_tablet&quot;:null,&quot;_transform_rotateX_effect_mobile&quot;:null,&quot;_transform_rotateY_effect&quot;:null,&quot;_transform_rotateY_effect_tablet&quot;:null,&quot;_transform_rotateY_effect_mobile&quot;:null,&quot;_transform_perspective_effect&quot;:null,&quot;_transform_perspective_effect_tablet&quot;:null,&quot;_transform_perspective_effect_mobile&quot;:null,&quot;_transform_translate_popover&quot;:&quot;&quot;,&quot;_transform_translateX_effect&quot;:null,&quot;_transform_translateX_effect_tablet&quot;:null,&quot;_transform_translateX_effect_mobile&quot;:null,&quot;_transform_translateY_effect&quot;:null,&quot;_transform_translateY_effect_tablet&quot;:null,&quot;_transform_translateY_effect_mobile&quot;:null,&quot;_transform_scale_popover&quot;:&quot;&quot;,&quot;_transform_keep_proportions&quot;:&quot;yes&quot;,&quot;_transform_scale_effect&quot;:null,&quot;_transform_scale_effect_tablet&quot;:null,&quot;_transform_scale_effect_mobile&quot;:null,&quot;_transform_scaleX_effect&quot;:null,&quot;_transform_scaleX_effect_tablet&quot;:null,&quot;_transform_scaleX_effect_mobile&quot;:null,&quot;_transform_scaleY_effect&quot;:null,&quot;_transform_scaleY_effect_tablet&quot;:null,&quot;_transform_scaleY_effect_mobile&quot;:null,&quot;_transform_skew_popover&quot;:&quot;&quot;,&quot;_transform_skewX_effect&quot;:null,&quot;_transform_skewX_effect_tablet&quot;:null,&quot;_transform_skewX_effect_mobile&quot;:null,&quot;_transform_skewY_effect&quot;:null,&quot;_transform_skewY_effect_tablet&quot;:null,&quot;_transform_skewY_effect_mobile&quot;:null,&quot;_transform_flipX_effect&quot;:&quot;&quot;,&quot;_transform_flipY_effect&quot;:&quot;&quot;,&quot;_transform_rotate_popover_hover&quot;:&quot;&quot;,&quot;_transform_rotateZ_effect_hover&quot;:null,&quot;_transform_rotateZ_effect_hover_tablet&quot;:null,&quot;_transform_rotateZ_effect_hover_mobile&quot;:null,&quot;_transform_rotate_3d_hover&quot;:null,&quot;_transform_rotateX_effect_hover&quot;:null,&quot;_transform_rotateX_effect_hover_tablet&quot;:null,&quot;_transform_rotateX_effect_hover_mobile&quot;:null,&quot;_transform_rotateY_effect_hover&quot;:null,&quot;_transform_rotateY_effect_hover_tablet&quot;:null,&quot;_transform_rotateY_effect_hover_mobile&quot;:null,&quot;_transform_perspective_effect_hover&quot;:null,&quot;_transform_perspective_effect_hover_tablet&quot;:null,&quot;_transform_perspective_effect_hover_mobile&quot;:null,&quot;_transform_translate_popover_hover&quot;:&quot;&quot;,&quot;_transform_translateX_effect_hover&quot;:null,&quot;_transform_translateX_effect_hover_tablet&quot;:null,&quot;_transform_translateX_effect_hover_mobile&quot;:null,&quot;_transform_translateY_effect_hover&quot;:null,&quot;_transform_translateY_effect_hover_tablet&quot;:null,&quot;_transform_translateY_effect_hover_mobile&quot;:null,&quot;_transform_scale_popover_hover&quot;:&quot;&quot;,&quot;_transform_keep_proportions_hover&quot;:&quot;yes&quot;,&quot;_transform_scale_effect_hover&quot;:null,&quot;_transform_scale_effect_hover_tablet&quot;:null,&quot;_transform_scale_effect_hover_mobile&quot;:null,&quot;_transform_scaleX_effect_hover&quot;:null,&quot;_transform_scaleX_effect_hover_tablet&quot;:null,&quot;_transform_scaleX_effect_hover_mobile&quot;:null,&quot;_transform_scaleY_effect_hover&quot;:null,&quot;_transform_scaleY_effect_hover_tablet&quot;:null,&quot;_transform_scaleY_effect_hover_mobile&quot;:null,&quot;_transform_skew_popover_hover&quot;:&quot;&quot;,&quot;_transform_skewX_effect_hover&quot;:null,&quot;_transform_skewX_effect_hover_tablet&quot;:null,&quot;_transform_skewX_effect_hover_mobile&quot;:null,&quot;_transform_skewY_effect_hover&quot;:null,&quot;_transform_skewY_effect_hover_tablet&quot;:null,&quot;_transform_skewY_effect_hover_mobile&quot;:null,&quot;_transform_flipX_effect_hover&quot;:&quot;&quot;,&quot;_transform_flipY_effect_hover&quot;:&quot;&quot;,&quot;_background_color&quot;:null,&quot;_background_color_b&quot;:null,&quot;_background_image&quot;:null,&quot;_background_video_link&quot;:null,&quot;_background_video_start&quot;:null,&quot;_background_video_end&quot;:null,&quot;_background_play_once&quot;:null,&quot;_background_play_on_mobile&quot;:null,&quot;_background_privacy_mode&quot;:null,&quot;_background_slideshow_gallery&quot;:null,&quot;_background_slideshow_loop&quot;:null,&quot;_background_slideshow_slide_duration&quot;:null,&quot;_background_slideshow_slide_transition&quot;:null,&quot;_background_slideshow_transition_duration&quot;:null,&quot;_background_slideshow_lazyload&quot;:null,&quot;_background_slideshow_ken_burns&quot;:null,&quot;_background_slideshow_ken_burns_zoom_direction&quot;:null,&quot;_background_hover_color&quot;:null,&quot;_background_hover_color_b&quot;:null,&quot;_background_hover_image&quot;:null,&quot;_background_hover_video_link&quot;:null,&quot;_background_hover_video_start&quot;:null,&quot;_background_hover_video_end&quot;:null,&quot;_background_hover_play_once&quot;:null,&quot;_background_hover_play_on_mobile&quot;:null,&quot;_background_hover_privacy_mode&quot;:null,&quot;_background_hover_slideshow_gallery&quot;:null,&quot;_background_hover_slideshow_loop&quot;:null,&quot;_background_hover_slideshow_slide_duration&quot;:null,&quot;_background_hover_slideshow_slide_transition&quot;:null,&quot;_background_hover_slideshow_transition_duration&quot;:null,&quot;_background_hover_slideshow_lazyload&quot;:null,&quot;_background_hover_slideshow_ken_burns&quot;:null,&quot;_background_hover_slideshow_ken_burns_zoom_direction&quot;:null,&quot;_mask_switch&quot;:&quot;&quot;,&quot;hide_desktop&quot;:&quot;&quot;,&quot;hide_tablet&quot;:&quot;&quot;,&quot;hide_mobile&quot;:&quot;&quot;,&quot;post_count&quot;:8,&quot;found_posts&quot;:12,&quot;query_args&quot;:{&quot;post_status&quot;:&quot;publish&quot;,&quot;posts_per_page&quot;:8,&quot;order&quot;:&quot;ASC&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;paged&quot;:1,&quot;post_type&quot;:&quot;portfolio&quot;},&quot;item_id&quot;:&quot;portfolio_module_6a57fc892c5db&quot;}' \/><\/form><\/div><\/div><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02f5a29 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02f5a29\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89de4b9\" data-id=\"89de4b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e4d5b elementor-widget elementor-widget-spacer\" data-id=\"55e4d5b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Business portfolio Our Case Studies We are specialists in both economics and information technologies and we apply our full range of talent to creating the perfect solution for each client\u2019s needs. All Workscorporatefinancemarketingstartupstrategy Information Technology corporatefinance Mobile App Startup startup People Professionalism marketingstrategy New Business Innovation corporatestrategy Customer Strategy startup Business Planning marketing Partnership System [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-44","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/pages\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":0,"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"wp:attachment":[{"href":"https:\/\/soycaribe.com\/index.php\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}